{"id":344,"date":"2019-02-03T17:01:24","date_gmt":"2019-02-03T16:01:24","guid":{"rendered":"http:\/\/corpusbio.com\/?p=344"},"modified":"2019-02-03T17:01:24","modified_gmt":"2019-02-03T16:01:24","slug":"les-vertus-du-curcuma","status":"publish","type":"post","link":"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/","title":{"rendered":"Les vertus du curcuma"},"content":{"rendered":"\n<p style=\"color:#207f31\" class=\"has-text-color has-medium-font-size\">Savez-vous que le curcuma est un bon protecteur ?<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/rhizome-et-poudre-de-curcuma-1024x681.jpg\" alt=\"\" class=\"wp-image-345\" srcset=\"https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/rhizome-et-poudre-de-curcuma-1024x681.jpg 1024w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/rhizome-et-poudre-de-curcuma-300x199.jpg 300w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/rhizome-et-poudre-de-curcuma-768x511.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>rhizome et poudre de curcuma<\/figcaption><\/figure>\n\n\n\n<p>Le <strong>curcuma<\/strong> est une \u00e9pice principalement indienne. On trouve le <strong>curcuma<\/strong> tr\u00e8s souvent en poudre mais \u00e9galement sous la forme de rhizome frais. C&rsquo;est une forte concentration en curcumine qui lui donne cette couleur orang\u00e9e. Si vous utilisez du <strong>curcuma<\/strong> frais, au moment de le r\u00e2per prot\u00e9gez-vous les doigts sinon ceux-ci resteront orang\u00e9s.<\/p>\n\n\n\n<p>Le <strong>curcuma<\/strong> est tr\u00e8s utilis\u00e9 dans la m\u00e9decine traditionnelle orientale. On lui conf\u00e8re de nombreuses vertus. C&rsquo;est l&rsquo;anti-inflammatoire naturel le plus puissant identifi\u00e9 \u00e0 ce jour. C&rsquo;est un antioxydant, un anti-stress et un anti-coagulant. Une action contre le diab\u00e8te lui est attribu\u00e9, tout comme contre le cancer (celui du sein, du colon, de la peau). Si des recherches sont toujours en cours \u00e0 ce sujet, on sait d\u00e9j\u00e0 que la curcumine prot\u00e8ge de l&rsquo;apparition d&rsquo;un cancer dans l&rsquo;organisme.<\/p>\n\n\n\n<p>En pr\u00e9vention je consomme au quotidien du<strong> curcuma<\/strong> en saupoudrant mes plats avec. Il ne faut pas d\u00e9passer la dose d&rsquo;une cuiller\u00e9e \u00e0 caf\u00e9 par jour. Je le m\u00e9lange \u00e0 du <strong>poivre noir<\/strong> afin de faciliter son absorption. Vous pouvez \u00e9galement le m\u00e9langer \u00e0 de l&rsquo;<strong>huile v\u00e9g\u00e9tale<\/strong>.<\/p>\n\n\n\n<p>Alors n&rsquo;h\u00e9sitez pas \u00e0 en consommer dans vos plats !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Savez-vous que le curcuma est un bon protecteur ? Le curcuma est une \u00e9pice principalement indienne. On trouve le curcuma tr\u00e8s souvent en poudre mais \u00e9galement sous la forme de rhizome frais. C&rsquo;est une forte concentration en curcumine qui lui donne cette couleur orang\u00e9e. Si vous utilisez du curcuma frais, au moment de le r\u00e2per &hellip; <a href=\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Les vertus du curcuma<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,90],"tags":[91,92],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les vertus du curcuma - CORPUS BIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vertus du curcuma - CORPUS BIO\" \/>\n<meta property=\"og:description\" content=\"Savez-vous que le curcuma est un bon protecteur ? Le curcuma est une \u00e9pice principalement indienne. On trouve le curcuma tr\u00e8s souvent en poudre mais \u00e9galement sous la forme de rhizome frais. C&rsquo;est une forte concentration en curcumine qui lui donne cette couleur orang\u00e9e. Si vous utilisez du curcuma frais, au moment de le r\u00e2per &hellip; Continuer la lecture de Les vertus du curcuma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/\" \/>\n<meta property=\"og:site_name\" content=\"CORPUS BIO\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-03T16:01:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/rhizome-et-poudre-de-curcuma-1024x681.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/corpusbio.com\/#website\",\"url\":\"https:\/\/corpusbio.com\/\",\"name\":\"CORPUS BIO\",\"description\":\"Comment se soigner naturellement\",\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/corpusbio.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/rhizome-et-poudre-de-curcuma-1024x681.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#webpage\",\"url\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/\",\"name\":\"Les vertus du curcuma - CORPUS BIO\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#primaryimage\"},\"datePublished\":\"2019-02-03T16:01:24+00:00\",\"dateModified\":\"2019-02-03T16:01:24+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#webpage\"},\"author\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"headline\":\"Les vertus du curcuma\",\"datePublished\":\"2019-02-03T16:01:24+00:00\",\"dateModified\":\"2019-02-03T16:01:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"image\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#primaryimage\"},\"keywords\":\"curcuma,poivre\",\"articleSection\":\"aliments essentiels,curcuma\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/02\/03\/les-vertus-du-curcuma\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\",\"name\":\"mimi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10f39ff057080fce202eaa979faeddc2?s=96&d=mm&r=g\",\"caption\":\"mimi\"},\"logo\":{\"@id\":\"https:\/\/corpusbio.com\/#personlogo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/344"}],"collection":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/comments?post=344"}],"version-history":[{"count":2,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/344\/revisions"}],"predecessor-version":[{"id":347,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/344\/revisions\/347"}],"wp:attachment":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/media?parent=344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/categories?post=344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/tags?post=344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}