{"id":348,"date":"2019-02-13T14:39:35","date_gmt":"2019-02-13T13:39:35","guid":{"rendered":"http:\/\/corpusbio.com\/?p=348"},"modified":"2019-02-13T14:39:35","modified_gmt":"2019-02-13T13:39:35","slug":"remede-naturel-contre-les-coupures-superficielles","status":"publish","type":"post","link":"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/","title":{"rendered":"Rem\u00e8de naturel contre les coupures superficielles"},"content":{"rendered":"\n<p style=\"color:#0f8840;font-size:24px\" class=\"has-text-color\"><strong>Savez-vous que le poivre noir arr\u00eate les saignements sur une coupure superficielle ?<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"475\" src=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/poivre-noir-1024x475.jpg\" alt=\"\" class=\"wp-image-351\" srcset=\"https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/poivre-noir-1024x475.jpg 1024w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/poivre-noir-300x139.jpg 300w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/poivre-noir-768x356.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>poivre noir<\/figcaption><\/figure>\n\n\n\n<p>On m&rsquo;avait parl\u00e9 du <strong>poivre noir<\/strong> pour ses vertus de cicatrisation. Je n&rsquo;y croyais pas trop jusqu&rsquo;au jour o\u00f9 j&rsquo;ai essay\u00e9. C&rsquo;est magique, je vous assure ! <\/p>\n\n\n\n<p>Au moment de peler mon fruit, je me suis coup\u00e9e \u00e0 la main. J&rsquo;ai aussit\u00f4t mis du <strong>poivre noir <\/strong>sur ma coupure. Deux secondes apr\u00e8s le sang avait coagul\u00e9. La plaie \u00e9tait referm\u00e9e. Magique ! On ressent des petits picotements au moment o\u00f9 le <strong>poivre<\/strong> agit mais ce n&rsquo;est pas douloureux. <\/p>\n\n\n\n<p>Le <strong>poivre<\/strong> <strong>noir<\/strong> est \u00e9galement un antiseptique naturel. Il n&rsquo;est donc pas n\u00e9cessaire de nettoyer la coupure au pr\u00e9alable.<\/p>\n\n\n\n<p>En cuisine, il peut arriver que le couteau d\u00e9rape au moment de couper les l\u00e9gumes ou lors de l&rsquo;ouverture des hu\u00eetres. Le <strong>poivre noir<\/strong> devient alors le rem\u00e8de naturel appropri\u00e9. Il est \u00e0 proximit\u00e9 et l&rsquo;arr\u00eat du saignement est imm\u00e9diat. Plus besoin de pansement ! On peut reprendre la cuisine sans g\u00eane.<\/p>\n\n\n\n<p><strong>Alors pensez au poivre noir !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Savez-vous que le poivre noir arr\u00eate les saignements sur une coupure superficielle ? On m&rsquo;avait parl\u00e9 du poivre noir pour ses vertus de cicatrisation. Je n&rsquo;y croyais pas trop jusqu&rsquo;au jour o\u00f9 j&rsquo;ai essay\u00e9. C&rsquo;est magique, je vous assure ! Au moment de peler mon fruit, je me suis coup\u00e9e \u00e0 la main. J&rsquo;ai aussit\u00f4t &hellip; <a href=\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Rem\u00e8de naturel contre les coupures superficielles<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[93,14],"tags":[94,92],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rem\u00e8de naturel contre les coupures superficielles - CORPUS BIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rem\u00e8de naturel contre les coupures superficielles - CORPUS BIO\" \/>\n<meta property=\"og:description\" content=\"Savez-vous que le poivre noir arr\u00eate les saignements sur une coupure superficielle ? On m&rsquo;avait parl\u00e9 du poivre noir pour ses vertus de cicatrisation. Je n&rsquo;y croyais pas trop jusqu&rsquo;au jour o\u00f9 j&rsquo;ai essay\u00e9. C&rsquo;est magique, je vous assure ! Au moment de peler mon fruit, je me suis coup\u00e9e \u00e0 la main. J&rsquo;ai aussit\u00f4t &hellip; Continuer la lecture de Rem\u00e8de naturel contre les coupures superficielles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/\" \/>\n<meta property=\"og:site_name\" content=\"CORPUS BIO\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-13T13:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/poivre-noir-1024x475.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/corpusbio.com\/#website\",\"url\":\"https:\/\/corpusbio.com\/\",\"name\":\"CORPUS BIO\",\"description\":\"Comment se soigner naturellement\",\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/corpusbio.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/02\/poivre-noir-1024x475.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#webpage\",\"url\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/\",\"name\":\"Rem\\u00e8de naturel contre les coupures superficielles - CORPUS BIO\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#primaryimage\"},\"datePublished\":\"2019-02-13T13:39:35+00:00\",\"dateModified\":\"2019-02-13T13:39:35+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#webpage\"},\"author\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"headline\":\"Rem\\u00e8de naturel contre les coupures superficielles\",\"datePublished\":\"2019-02-13T13:39:35+00:00\",\"dateModified\":\"2019-02-13T13:39:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"image\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#primaryimage\"},\"keywords\":\"coupure,poivre\",\"articleSection\":\"poivre,th\\u00e8me dermatologique\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/02\/13\/remede-naturel-contre-les-coupures-superficielles\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\",\"name\":\"mimi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10f39ff057080fce202eaa979faeddc2?s=96&d=mm&r=g\",\"caption\":\"mimi\"},\"logo\":{\"@id\":\"https:\/\/corpusbio.com\/#personlogo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/348"}],"collection":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/comments?post=348"}],"version-history":[{"count":3,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/348\/revisions"}],"predecessor-version":[{"id":353,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/348\/revisions\/353"}],"wp:attachment":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/media?parent=348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/categories?post=348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/tags?post=348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}