{"id":414,"date":"2019-05-14T19:45:22","date_gmt":"2019-05-14T17:45:22","guid":{"rendered":"http:\/\/corpusbio.com\/?p=414"},"modified":"2019-05-14T19:45:23","modified_gmt":"2019-05-14T17:45:23","slug":"theme-du-livre-les-dessous-de-la-charcuterie","status":"publish","type":"post","link":"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/","title":{"rendered":"Th\u00e8me du livre : les dessous de la charcuterie"},"content":{"rendered":"\n<p style=\"color:#1c8d27\" class=\"has-text-color has-large-font-size\">Suggestion de livres \u00e0 lire<\/p>\n\n\n\n<p>Depuis toujours dans notre gastronomie fran\u00e7aise, la <strong>charcuterie<\/strong> est un produit phare r\u00e9gional. Fabriqu\u00e9s selon la tradition tout en respectant l&rsquo;animal, j&rsquo;ai toujours l&rsquo;image des jambons suspendus pendant des mois dans la cave afin qu&rsquo;ils d\u00e9gagent leur saveur. Confiante, je ne pensais pas qu&rsquo;en mangeant de la charcuterie, je mettais mon corps en danger. Depuis que j&rsquo;ai lu ce livre: \u00ab\u00a0<strong>Cochonneries &#8211; Comment la charcuterie est devenue un poison\u00a0\u00bb de Guillaume COUDRAY, chez La D\u00e9couverte, \u00e9dit\u00e9e en 2017<\/strong>, mon avis a chang\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"653\" height=\"1024\" src=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison-653x1024.jpg\" alt=\"\" class=\"wp-image-415\" srcset=\"https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison-653x1024.jpg 653w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison-191x300.jpg 191w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison-768x1205.jpg 768w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison.jpg 1630w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/><figcaption><strong>COCHONNERIES<br>comment la charcuterie est devenu un poison <br>de Guillaume Coudray<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Actuellement la fabrication de la<strong> charcuterie<\/strong> est tout autre. Beaucoup de fabricants traditionnels ou industriels utilisent du nitrate de potassium et\/ou du nitrite de sodium pour acc\u00e9l\u00e9rer le produit fini afin de faire du profit. Or ces additifs sont n\u00e9fastes pour la sant\u00e9.<\/p>\n\n\n\n<p>Depuis, d\u00e8s que j&rsquo;ach\u00e8te de la charcuterie, en particulier le saucisson, grande amatrice, je lis les \u00e9tiquettes scrupuleusement. Je peux vous dire qu&rsquo;il est difficile de trouver un produit sans additifs m\u00eame dans les produits dits traditionnels ou bio mais j&rsquo;y arrive.<\/p>\n\n\n\n<p>Alors n&rsquo;h\u00e9sitez pas \u00e0 lire cette enqu\u00eate tr\u00e8s bien men\u00e9e. Vous avez le droit de savoir comment est fabriqu\u00e9e la charcuterie que vous consommez ! Donnez-moi votre avis ? <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suggestion de livres \u00e0 lire Depuis toujours dans notre gastronomie fran\u00e7aise, la charcuterie est un produit phare r\u00e9gional. Fabriqu\u00e9s selon la tradition tout en respectant l&rsquo;animal, j&rsquo;ai toujours l&rsquo;image des jambons suspendus pendant des mois dans la cave afin qu&rsquo;ils d\u00e9gagent leur saveur. Confiante, je ne pensais pas qu&rsquo;en mangeant de la charcuterie, je mettais &hellip; <a href=\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Th\u00e8me du livre : les dessous de la charcuterie<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[123,58],"tags":[124,125],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Th\u00e8me du livre : les dessous de la charcuterie - CORPUS BIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Th\u00e8me du livre : les dessous de la charcuterie - CORPUS BIO\" \/>\n<meta property=\"og:description\" content=\"Suggestion de livres \u00e0 lire Depuis toujours dans notre gastronomie fran\u00e7aise, la charcuterie est un produit phare r\u00e9gional. Fabriqu\u00e9s selon la tradition tout en respectant l&rsquo;animal, j&rsquo;ai toujours l&rsquo;image des jambons suspendus pendant des mois dans la cave afin qu&rsquo;ils d\u00e9gagent leur saveur. Confiante, je ne pensais pas qu&rsquo;en mangeant de la charcuterie, je mettais &hellip; Continuer la lecture de Th\u00e8me du livre : les dessous de la charcuterie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/\" \/>\n<meta property=\"og:site_name\" content=\"CORPUS BIO\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-14T17:45:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-14T17:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison-653x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/corpusbio.com\/#website\",\"url\":\"https:\/\/corpusbio.com\/\",\"name\":\"CORPUS BIO\",\"description\":\"Comment se soigner naturellement\",\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/corpusbio.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/05\/COCHONNERIES-Comment-al-charcuterie-est-devenu-un-poison-653x1024.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#webpage\",\"url\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/\",\"name\":\"Th\\u00e8me du livre : les dessous de la charcuterie - CORPUS BIO\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#primaryimage\"},\"datePublished\":\"2019-05-14T17:45:22+00:00\",\"dateModified\":\"2019-05-14T17:45:23+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#webpage\"},\"author\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"headline\":\"Th\\u00e8me du livre : les dessous de la charcuterie\",\"datePublished\":\"2019-05-14T17:45:22+00:00\",\"dateModified\":\"2019-05-14T17:45:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"image\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#primaryimage\"},\"keywords\":\"additifs,charcuterie\",\"articleSection\":\"charcuterie,suggestions de livres \\u00e0 lire\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/05\/14\/theme-du-livre-les-dessous-de-la-charcuterie\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\",\"name\":\"mimi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10f39ff057080fce202eaa979faeddc2?s=96&d=mm&r=g\",\"caption\":\"mimi\"},\"logo\":{\"@id\":\"https:\/\/corpusbio.com\/#personlogo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/414"}],"collection":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/comments?post=414"}],"version-history":[{"count":8,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/414\/revisions"}],"predecessor-version":[{"id":426,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/414\/revisions\/426"}],"wp:attachment":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/media?parent=414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/categories?post=414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/tags?post=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}