{"id":435,"date":"2019-06-09T16:15:59","date_gmt":"2019-06-09T14:15:59","guid":{"rendered":"http:\/\/corpusbio.com\/?p=435"},"modified":"2019-06-09T16:16:00","modified_gmt":"2019-06-09T14:16:00","slug":"les-vertus-de-labricot","status":"publish","type":"post","link":"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/","title":{"rendered":"Les vertus de l&rsquo;abricot"},"content":{"rendered":"\n<p style=\"color:#03a300;font-size:25px\" class=\"has-text-color\">Savez-vous que l&rsquo;abricot regorge de vitamines ?<\/p>\n\n\n\n<p>Les fruits d&rsquo;\u00e9t\u00e9 arrivent. Ils nous rafra\u00eechissent en p\u00e9riode de chaleur. L&rsquo;<strong>abricot<\/strong> fait partie de ces fruits. \u00c7a tombe bien, il fait son apparition sur les \u00e9tals. Sa chair sucr\u00e9e, peu juteuse, jaune orang\u00e9 et ferme est tr\u00e8s nutritive.<\/p>\n\n\n\n<p>En effet, l&rsquo;<strong>abricot<\/strong> est riche en vitamine A (b\u00eata-carot\u00e8ne) qui est n\u00e9cessaire pour la croissance des os et pour la vision cr\u00e9pusculaire. Son r\u00f4le anti-oxydant par sa richesse en carot\u00e8ne combat le vieillissement cellulaire. L&rsquo;<strong>abricot<\/strong> est compos\u00e9 \u00e9galement de vitamine B, C, de sels min\u00e9raux et d&rsquo;oligo-\u00e9l\u00e9ments : magn\u00e9sium, phosphore, fer, calcium, potassium, fluor&#8230;.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot-1024x768.jpg\" alt=\"\" class=\"wp-image-436\" srcset=\"https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot-1024x768.jpg 1024w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot-300x225.jpg 300w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot-768x576.jpg 768w, https:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>abricots<\/figcaption><\/figure>\n\n\n\n<p>Mais aussi, l&rsquo;<strong>abricot<\/strong> augmente les r\u00e9actions naturelles de d\u00e9fense. Il fournit pour 100g en moyenne, 45% de notre besoin en vitamine A par jour, 8% de vitamine C, 5% de vitamine B1, et 3% de vitamine B2.<\/p>\n\n\n\n<p>Vous l&rsquo;aurez compris, l&rsquo;<strong>abricot<\/strong> est un fruit essentiel \u00e0 notre m\u00e9tabolisme. Pour ceux qui arrosent un peu trop leur soir\u00e9e, ce fruit par sa teneur en vitamine B1 favorise la d\u00e9gradation de l&rsquo;alcool par le foie.<strong> <\/strong>N&rsquo;h\u00e9sitez pas \u00e0 en manger !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Savez-vous que l&rsquo;abricot regorge de vitamines ? Les fruits d&rsquo;\u00e9t\u00e9 arrivent. Ils nous rafra\u00eechissent en p\u00e9riode de chaleur. L&rsquo;abricot fait partie de ces fruits. \u00c7a tombe bien, il fait son apparition sur les \u00e9tals. Sa chair sucr\u00e9e, peu juteuse, jaune orang\u00e9 et ferme est tr\u00e8s nutritive. En effet, l&rsquo;abricot est riche en vitamine A (b\u00eata-carot\u00e8ne) &hellip; <a href=\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Les vertus de l&rsquo;abricot<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[130,78],"tags":[131,122,132,133],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les vertus de l&#039;abricot - CORPUS BIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vertus de l&#039;abricot - CORPUS BIO\" \/>\n<meta property=\"og:description\" content=\"Savez-vous que l&rsquo;abricot regorge de vitamines ? Les fruits d&rsquo;\u00e9t\u00e9 arrivent. Ils nous rafra\u00eechissent en p\u00e9riode de chaleur. L&rsquo;abricot fait partie de ces fruits. \u00c7a tombe bien, il fait son apparition sur les \u00e9tals. Sa chair sucr\u00e9e, peu juteuse, jaune orang\u00e9 et ferme est tr\u00e8s nutritive. En effet, l&rsquo;abricot est riche en vitamine A (b\u00eata-carot\u00e8ne) &hellip; Continuer la lecture de Les vertus de l&rsquo;abricot\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/\" \/>\n<meta property=\"og:site_name\" content=\"CORPUS BIO\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-09T14:15:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-09T14:16:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot-1024x768.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/corpusbio.com\/#website\",\"url\":\"https:\/\/corpusbio.com\/\",\"name\":\"CORPUS BIO\",\"description\":\"Comment se soigner naturellement\",\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/corpusbio.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/corpusbio.com\/wp-content\/uploads\/2019\/06\/abricot-1024x768.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#webpage\",\"url\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/\",\"name\":\"Les vertus de l'abricot - CORPUS BIO\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#primaryimage\"},\"datePublished\":\"2019-06-09T14:15:59+00:00\",\"dateModified\":\"2019-06-09T14:16:00+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#webpage\"},\"author\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"headline\":\"Les vertus de l&rsquo;abricot\",\"datePublished\":\"2019-06-09T14:15:59+00:00\",\"dateModified\":\"2019-06-09T14:16:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\"},\"image\":{\"@id\":\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#primaryimage\"},\"keywords\":\"abricot,anti-oxydant,nutritif,vitamine\",\"articleSection\":\"abricot,aliments essentiels\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/corpusbio.com\/index.php\/2019\/06\/09\/les-vertus-de-labricot\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/corpusbio.com\/#\/schema\/person\/bdd5055130559d410a04c64c076875ce\",\"name\":\"mimi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/corpusbio.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10f39ff057080fce202eaa979faeddc2?s=96&d=mm&r=g\",\"caption\":\"mimi\"},\"logo\":{\"@id\":\"https:\/\/corpusbio.com\/#personlogo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/435"}],"collection":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/comments?post=435"}],"version-history":[{"count":6,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/435\/revisions"}],"predecessor-version":[{"id":442,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/posts\/435\/revisions\/442"}],"wp:attachment":[{"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/media?parent=435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/categories?post=435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpusbio.com\/index.php\/wp-json\/wp\/v2\/tags?post=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}